{"id":83257,"date":"2018-03-20T17:15:19","date_gmt":"2018-03-20T17:15:19","guid":{"rendered":"https:\/\/wordpress.org\/plugins\/exclusivo-entrada-complemento\/"},"modified":"2018-03-28T13:14:14","modified_gmt":"2018-03-28T13:14:14","slug":"exclusivo-entrada-complemento","status":"publish","type":"plugin","link":"https:\/\/bre.wordpress.org\/plugins\/exclusivo-entrada-complemento\/","author":6179185,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"1.0.3","stable_tag":"trunk","tested":"4.9.31","requires":"4.3","requires_php":"5.2.4","requires_plugins":"","header_name":"Exclusivo entrada complemento","header_author":"Ernesto Tur Laurencio","header_description":"Plugin de Wordpress para a\u00f1adir una frase o palabra ante cada t\u00edtulo de entrada a mostrar","assets_banners_color":"","last_updated":"2018-03-28 13:14:14","external_support_url":"","external_repository_url":"","donate_link":"https:\/\/blockchain.info\/payment_request?address=15gi3bKMptcCQPjM18ZogLkVWgxLAERnC7&amount_local=1&currency=USD&nosavecurrency=true&message=Never%20reject%20gold%20given","header_plugin_uri":"https:\/\/github.com\/sasousuke\/exclusivo-entrada-plugin","header_author_uri":"https:\/\/twitter.com\/sasousuke","rating":0,"author_block_rating":0,"active_installs":10,"downloads":1452,"num_ratings":0,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","changelog","faq"],"tags":[],"upgrade_notice":{"":"<ul>\n<li>Modificado la seleccion de categoria (Ya no aparece el contador de entradas pertenecientes a la categoria)<\/li>\n<\/ul>"},"ratings":{"1":0,"2":0,"3":0,"4":0,"5":0},"assets_icons":[],"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":["1.0.1","1.0.2","1.0.3"],"block_files":[],"assets_screenshots":[],"screenshots":{"1":"<code>\/assets\/screenshot-1.png<\/code>"}},"plugin_section":[],"plugin_tags":[610,86],"plugin_category":[57],"plugin_contributors":[154588],"plugin_business_model":[],"class_list":["post-83257","plugin","type-plugin","status-publish","hentry","plugin_tags-categories","plugin_tags-post","plugin_category-taxonomy","plugin_contributors-sasousuke","plugin_committers-sasousuke"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/s.w.org\/plugins\/geopattern-icon\/exclusivo-entrada-complemento.svg","icon_2x":false,"generated":true},"screenshots":[],"raw_content":"<!--section=description-->\n<p>El objetivo de este plugin es que se anada alguna frase o palabra(s) al titulo de todas las entradas pertenecientes\na una categoria dentro de nuestro sitio creado con WordPress.<\/p>\n\n<!--section=installation-->\n<ol>\n<li>Suba el contenido del plugin en <code>\/wp-content\/plugins\/plugin-name<\/code> , o instalelo desde el apartado de plugin de WordPress.<\/li>\n<li>Active el plugin en el apartado de 'Plugins' de su sitio.<\/li>\n<li>Modifique las configuraciones en la opcion \"Exclusivo Entrada Plugin\" del Menu Principal<\/li>\n<\/ol>\n\n<!--section=changelog-->\n<h4>1.0.3<\/h4>\n\n<ul>\n<li>Modificado la seleccion de categoria (Ya no aparece el contador de entradas pertenecientes a la categoria).<\/li>\n<li>Optimizaciones.<\/li>\n<\/ul>\n\n<h4>1.0.2<\/h4>\n\n<ul>\n<li>Anadido seleccion de categoria.<\/li>\n<li>Enmaquetado HTML para mejor visualizacion de configuraciones.<\/li>\n<\/ul>\n\n<h4>1.0.1<\/h4>\n\n<ul>\n<li>Anadido apartado de configuraciones.<\/li>\n<\/ul>\n\n<h4>1.0.0<\/h4>\n\n<ul>\n<li>Beta Plugin.<\/li>\n<\/ul>\n\n<!--section=faq-->\n<dl>\n<dt>Installation Instructions<\/dt>\n<dd><ol>\n<li>Suba el contenido del plugin en <code>\/wp-content\/plugins\/plugin-name<\/code> , o instalelo desde el apartado de plugin de WordPress.<\/li>\n<li>Active el plugin en el apartado de 'Plugins' de su sitio.<\/li>\n<li>Modifique las configuraciones en la opcion \"Exclusivo Entrada Plugin\" del Menu Principal<\/li>\n<\/ol><\/dd>\n\n<\/dl>","raw_excerpt":"Plugin de WordPress para anadir una frase o palabra ante cada titulo de entrada a mostrar.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/83257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=83257"}],"author":[{"embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/sasousuke"}],"wp:attachment":[{"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=83257"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=83257"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=83257"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=83257"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=83257"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/bre.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=83257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}